{"id":27,"count":3,"description":"","link":"https:\/\/www.darsenamossa.com\/en\/category\/organizza-la-tua-vita-in-viaggio\/scambiare-la-propria-abitazione\/","name":"Scambiare la Propria Abitazione","slug":"scambiare-la-propria-abitazione","taxonomy":"category","parent":13,"meta":[],"_links":{"self":[{"href":"https:\/\/www.darsenamossa.com\/en\/wp-json\/wp\/v2\/categories\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darsenamossa.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.darsenamossa.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.darsenamossa.com\/en\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/www.darsenamossa.com\/en\/wp-json\/wp\/v2\/posts?categories=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}